{"id":31107,"date":"2016-11-22T21:28:08","date_gmt":"2016-11-22T21:28:08","guid":{"rendered":"https:\/\/atravesdelasescrituras.com\/?p=31107"},"modified":"2016-11-22T21:32:16","modified_gmt":"2016-11-22T21:32:16","slug":"prince-of-peace","status":"publish","type":"post","link":"https:\/\/atravesdelasescrituras.com\/es_es\/2016\/11\/22\/prince-of-peace\/","title":{"rendered":"Prince of Peace"},"content":{"rendered":"<p>Hoy tuve un d\u00eda muy cansado y alborotado, les dejo una bella canci\u00f3n &#8211; Principe de Paz, Shalom&#8230; Grabada desde Jerusalem\u00a0en memoria\u00a0de la guerra&#8230;<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" width=\"1870\" height=\"1052\" src=\"https:\/\/www.youtube.com\/embed\/rIqUTMHl9Cs?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy tuve un d\u00eda muy cansado y alborotado, les dejo una bella canci\u00f3n &#8211; Principe de Paz, Shalom&#8230; Grabada desde Jerusalem\u00a0en memoria\u00a0de la guerra&#8230;<\/p>\n","protected":false},"author":80235555,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_gspb_post_css":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1790,1149],"tags":[152203,8329,548996486,1725756,4993702,81877,162114],"class_list":["post-31107","post","type-post","status-publish","format-standard","hentry","category-otros","category-videos","tag-hillsong","tag-jesus","tag-of-dirty-and-grace","tag-prince-of-peace","tag-principe-de-paz","tag-shalom","tag-yeshua"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5HWJ5-85J","jetpack-related-posts":[{"id":51488,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2024\/10\/09\/daniel-924-27-una-profecia-de-cristo\/","url_meta":{"origin":31107,"position":0},"title":"Daniel 9:24-27 \u00abLas 70 semanas de Daniel\u00bb \u00bfUna profec\u00eda de Cristo?","author":"Daniel L\u00f3pez","date":"9 Oct 2024","format":false,"excerpt":"\u00bfEra exacta la profec\u00eda de Daniel sobre la venida del \u00abUngido\u00bb, es decir, del Mes\u00edas? \u00bfO se ha interpretado err\u00f3neamente el texto y hay un Mes\u00edas que viene al final de la primera serie de siete sietes, es decir, al final de 49 a\u00f1os, y otro Mes\u00edas que viene al\u2026","rel":"","context":"En \u00abArt\u00edculos varios\u00bb","block_context":{"text":"Art\u00edculos varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/articulos-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/10\/70-semanas-de-daniel.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/10\/70-semanas-de-daniel.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/10\/70-semanas-de-daniel.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/10\/70-semanas-de-daniel.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/10\/70-semanas-de-daniel.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42204,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2020\/07\/05\/sobre-la-parasha-pinjas\/","url_meta":{"origin":31107,"position":1},"title":"Sobre la Parashat Pinjas","author":"Daniel L\u00f3pez","date":"5 Jul 2020","format":"gallery","excerpt":"En esta semana estamos estudiando la Parash\u00e1 Pinjas se encuentra en:\u00a0N\u00fameros 25:10-30:1\u2014\u00a0\u05e4\u05b4\u05bc\u05d9\u05e0\u05b0\u05d7\u05b8\u05e1\u00a0(Pinjas)\u00a0significa: \u201cFinees\u201c. Leemos al final de la parash\u00e1 anterior (Balaq) el pecado que dio suceso a una mortandad terrible entre los hijos de Israel: N\u00fameros 25:1-3 - \"...Israel acude a Baal-peor Moraba Israel en Sitim; y el pueblo empez\u00f3\u2026","rel":"","context":"En \u00abEstudios B\u00edblicos\u00bb","block_context":{"text":"Estudios B\u00edblicos","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/estudios-biblicos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2020\/07\/parashat-pinjas.jpg?fit=1200%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2020\/07\/parashat-pinjas.jpg?fit=1200%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2020\/07\/parashat-pinjas.jpg?fit=1200%2C480&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2020\/07\/parashat-pinjas.jpg?fit=1200%2C480&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2020\/07\/parashat-pinjas.jpg?fit=1200%2C480&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40237,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/03\/20\/levitico-3-leyes-sobre-ofrendas-de-paz-shelamim\/","url_meta":{"origin":31107,"position":2},"title":"Lev\u00edtico 3 &#8211; Leyes sobre ofrendas de Paz (Shelamim)","author":"Daniel L\u00f3pez","date":"20 Mar 2019","format":"gallery","excerpt":"La tercera clase de sacrificio es llamada \u05e9\u05dc\u05de\u05d9\u05dd , \u05d6\u05d1\u05d7 com\u00fanmente interpretada como ofrenda de agradecimiento, pero m\u00e1s correctamente como ofrenda de salvaci\u00f3n. Adem\u00e1s de esta forma m\u00e1s completa, que es la m\u00e1s com\u00fanmente empleada en Lev\u00edtico, nos encontramos con las formas abreviadas de \u05d6\u05d1\u05d7\u05d9\u05dd , \u05e9\u05dc\u05de\u05d9\u05dd, en los caps.\u2026","rel":"","context":"En \u00abEstudios B\u00edblicos\u00bb","block_context":{"text":"Estudios B\u00edblicos","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/estudios-biblicos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/03\/portada-lev3.jpg?fit=1200%2C493&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/03\/portada-lev3.jpg?fit=1200%2C493&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/03\/portada-lev3.jpg?fit=1200%2C493&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/03\/portada-lev3.jpg?fit=1200%2C493&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/03\/portada-lev3.jpg?fit=1200%2C493&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39961,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2018\/12\/29\/el-mesias-hijo-de-david-hijo-de-dios\/","url_meta":{"origin":31107,"position":3},"title":"El Mes\u00edas hijo de David &#8211; Hijo de Dios","author":"Daniel L\u00f3pez","date":"29 Dic 2018","format":"gallery","excerpt":"El Mes\u00edas habr\u00eda de descender de la simiente de Eva, de Set, de Abraham, Isaac, y Jacob, y de Jud\u00e1 e Isa\u00ed. La \u201cvara\u201d mesi\u00e1nica pasa ahora a David el hijo de Isa\u00ed. Esto se confirma por las siguientes palabras habladas por Nat\u00e1n, el Profeta, y dirigidas a David: 2\u2026","rel":"","context":"En \u00abEstudios Varios\u00bb","block_context":{"text":"Estudios Varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/estudios-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2018\/12\/david.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2018\/12\/david.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2018\/12\/david.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2018\/12\/david.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2018\/12\/david.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2018\/12\/david.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":21306,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2016\/09\/24\/comentarios-de-rabinos-sobre-el-mesias\/","url_meta":{"origin":31107,"position":4},"title":"Comentarios de rabinos sobre el Mes\u00edas","author":"Daniel L\u00f3pez","date":"24 Sep 2016","format":"gallery","excerpt":"El Rab\u00ed Mois\u00e9s Abraham Lev\u00ed dijo lo siguiente sobre la venida del Mes\u00edas: \u201cHe examinado e investigado todas las sagradas\u00a0\u00a0escrituras y no he hallado el tiempo para la venida del Mes\u00edas claramente fijado, excepto en las palabras de Gabriel al profeta Daniel, que est\u00e1n escritas en el cap\u00edtulo 9 de\u2026","rel":"","context":"En \u00abArt\u00edculos varios\u00bb","block_context":{"text":"Art\u00edculos varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/articulos-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/09\/10-seventy.gif?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/09\/10-seventy.gif?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/09\/10-seventy.gif?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/09\/10-seventy.gif?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/09\/10-seventy.gif?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":52094,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2024\/12\/25\/el-significado-del-mesias-y-sus-titulos\/","url_meta":{"origin":31107,"position":5},"title":"El significado del Mes\u00edas y sus t\u00edtulos","author":"Daniel L\u00f3pez","date":"25 Dic 2024","format":false,"excerpt":"En este art\u00edculo veremos un an\u00e1lisis exhaustivo de la figura mesi\u00e1nica tal y como se describe en el Antiguo Testamento. Profundiza en los or\u00edgenes hebreos del t\u00e9rmino \"Mes\u00edas\" y explora los diversos t\u00edtulos y atributos asociados a esta figura anticipada.","rel":"","context":"En \u00abArt\u00edculos varios\u00bb","block_context":{"text":"Art\u00edculos varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/articulos-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/12\/el-mesias.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/12\/el-mesias.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/12\/el-mesias.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/12\/el-mesias.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/12\/el-mesias.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"brizy_media":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/31107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/users\/80235555"}],"replies":[{"embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/comments?post=31107"}],"version-history":[{"count":5,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/31107\/revisions"}],"predecessor-version":[{"id":31112,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/31107\/revisions\/31112"}],"wp:attachment":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/media?parent=31107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/categories?post=31107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/tags?post=31107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}