{"id":40579,"date":"2019-05-23T13:22:33","date_gmt":"2019-05-23T13:22:33","guid":{"rendered":"http:\/\/atravesdelasescrituras.com\/?p=40579"},"modified":"2019-05-23T13:22:33","modified_gmt":"2019-05-23T13:22:33","slug":"critica-textual-del-nuevo-testamento","status":"publish","type":"post","link":"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/05\/23\/critica-textual-del-nuevo-testamento\/","title":{"rendered":"Critica textual del Nuevo Testamento"},"content":{"rendered":"\n<ul class=\"wp-block-gallery columns-0 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A) Los Manuscritos del Nuevo Testamento<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Papiros:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se nos conservan 118 papiros con textos o fragmentos del NT.\nSe citan con una p acompa\u00f1ada del n\u00famero del cat\u00e1logo. Son los manuscritos m\u00e1s\nantiguos. Los m\u00e1s importantes para el NT est\u00e1n en tres colecciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Rylands (Manchester), por ejemplo p52 el fragmento m\u00e1s antiguo.<\/li><li>Chester Beatty (Dubl\u00edn), por ejemplo el p45 con gran parte de los evangelios.<\/li><li>Bodmer (Ginebra), por ejemplo los p66 y p75 con el texto de Juan.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">2. Pergaminos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hay de dos clases: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration:underline;\">Unciales<\/span>: (escritos con letras may\u00fasculas: del siglo III al IX). De ellos se nos conservan actualmente unos 250. Los m\u00e1s antiguos y de mayor valor son el Sina\u00edtico (Londres) y el Vaticano (Roma) de los siglos III-IV.<\/p>\n\n\n\n<table class=\"wp-block-table\"><tbody><tr><td>      <img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"678\" data-attachment-id=\"40580\" data-permalink=\"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/05\/23\/critica-textual-del-nuevo-testamento\/sinaiticus\/\" data-orig-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/sinaiticus.jpg\" data-orig-size=\"600,407\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"sinaiticus\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/sinaiticus.jpg\" class=\"wp-image-40580\" style=\"width:1000px;\" src=\"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/sinaiticus.jpg?resize=1000%2C678&#038;ssl=1\" alt=\"undefined\"> <\/td><td>      <img data-recalc-dims=\"1\" decoding=\"async\" width=\"1000\" height=\"678\" data-attachment-id=\"40581\" data-permalink=\"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/05\/23\/critica-textual-del-nuevo-testamento\/vaticanus\/\" data-orig-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/vaticanus.jpg\" data-orig-size=\"600,407\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Vaticanus\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/vaticanus.jpg\" class=\"wp-image-40581\" style=\"width:1000px;\" src=\"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/vaticanus.jpg?resize=1000%2C678&#038;ssl=1\" alt=\"undefined\"> <\/td><\/tr><tr><td>\n  P\u00e1gina del c\u00f3dice sina\u00edtico\n  <\/td><td>\n  P\u00e1gina del c\u00f3dice Vaticano\n  <\/td><\/tr><\/tbody><\/table>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration:underline;\">Min\u00fasculos<\/span>: a partir del siglo IX. A pesar de ser m\u00e1s recientes, pueden tener mucho valor si se copiaron de un original muy antiguo. Existen unos 2.700 c\u00f3dices min\u00fasculos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Leccionarios:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son antolog\u00edas de textos b\u00edblicos para uso lit\u00fargico.\nExisten actualmente unos 2.000 leccionarios manuscritos, anteriores a la\ninvenci\u00f3n de la imprenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Traducciones:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Biblia se tradujo desde muy pronto a otras lenguas de la\nantig\u00fcedad, que nos aportan datos muy valiosos para reconstruir los originales\ndesde los que se hizo la traducci\u00f3n. Hay dos traducciones al lat\u00edn, la Vetus\nLatina y la Vulgata, y otras traducciones al sir\u00edaco, el copto, el armenio,\ngeorgiano&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Citas de los Antiguos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son otro testimonio muy importante que hay que cotejar. Aunque a veces los antiguos citaban de memoria, sin embargo en muchos casos estas citas son muy \u00fatiles para rastrear qu\u00e9 dec\u00edan los c\u00f3dices b\u00edblicos que ellos utilizaban.\u00a0<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>B) El problema de las variantes textuales:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los m\u00e1s de 3.000 manuscritos que poseemos del NT, apenas\nhabr\u00e1 un solo vers\u00edculo en el que coincidan a la vez todos los manuscritos\npalabra por palabra o letra por letra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe encontrar m\u00e1s de 300.000 variantes en el NT. \u00bfCu\u00e1l de\nellas escoger? \u00bfC\u00f3mo recomponer las palabras exactas tal como salieron de la\npluma del escritor sagrado en el original aut\u00f3grafo? Sobre este tema versa la\nciencia que denominamos cr\u00edtica textual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de esta primera impresi\u00f3n penosa de los cientos de\nmiles de variantes, sin embargo, al profundizar, nos damos cuenta de que muchas\nde estas variantes se detectan inmediatamente como errores del copista, y\npueden descartarse sin m\u00e1s. Podemos decir que hoy d\u00eda tenemos seguridad sobre\nel texto original del Nuevo Testamento en m\u00e1s de un 90% de su extensi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del 10% restante, del que puede caber alguna duda, la inmensa mayor\u00eda de las variantes no afectan para nada al sentido de los textos, sino s\u00f3lo al orden de dos palabras, a la presencia o ausencia de una part\u00edcula. \u00a0<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C) Los errores del copista:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Cambios accidentales:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pueden venir de confusi\u00f3n de letras; la haplograf\u00eda consiste\nen simplificar algo que estaba duplicado; la diptograf\u00eda que consiste en\nduplicar algo que era simple. Tanto la haplograf\u00eda como la diptograf\u00eda pueden\nafectar a una letra, una palabra, o un p\u00e1rrafo entero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es frecuente saltarse una l\u00ednea, o saltarse una l\u00ednea cuando dos l\u00edneas terminan en la misma palabra (<em>homoteleuton<\/em>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Cambios intencionales:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pueden nacer del deseo de modernizar alguna palabra que ha\nquedado arcaica, o de corregir alg\u00fan error geogr\u00e1fico o sint\u00e1ctico, o de\nexplicar con una glosa algo que no se entiende bien, o de censurar alguna\npalabra o concreto que puede resultar extra\u00f1o o malsonante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n son frecuentes los cambios intencionales nacidos del\ndeseo de armonizar una lectura con la lectura paralela de otros textos\nsin\u00f3pticos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pueden nacer del deseo e modernizar una palabra que ya ha quedado arcaica.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D) Razones y objetivos de la cr\u00edtica textual\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cr\u00edtica textual es una disciplina que se aplica a todos\nlos autores literarios antiguos cuyas obras nos han llegado en copias\nmanuscritas que contienen variantes textuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;1. Razones de la cr\u00edtica textual<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>P\u00e9rdida de originales y aut\u00f3grafos.<\/li><li>Variantes, lagunas, glosas y errores producidas por los copistas.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">2. Objetivos de la cr\u00edtica textual<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Reconstruir la historia de la transmisi\u00f3n del texto.<\/li><li>Restaurar el texto en su estado original en la medida en que esto es posible.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que comienza a imprimirse el texto griego del NT en el\nsiglo XVI empieza a darse un esfuerzo de los editores por basar su trabajo\nsobre c\u00f3dices griegos valiosos, confrontando las lecturas variantes. M\u00e1s tarde\nse empieza ya a compilar variantes en trabajos eruditos. Pero la cr\u00edtica\ntextual como ciencia s\u00f3lo comienza a principios del XIX con Griesbach que\nestablece ya la metodolog\u00eda, y cataloga las familias de los manuscritos seg\u00fan\nsu proximidad textual. Es el primero que se aventura a abandonar el textus\nreceptus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cr\u00edtica textual alcanza su madurez en la obra de Von Tischendorf (<em>1815-1874<\/em>), el descubridor del c\u00f3dice sina\u00edtico. Tischendorf publica grandes ediciones del texto griego con aparato cr\u00edtico amplio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde entonces se ha sucedido un conocimiento mucho m\u00e1s completo de c\u00f3dices hasta entonces desconocidos, se han discernido relaciones de unos c\u00f3dices con otros hasta agruparlos en familias, y se ha mejorado la criteriolog\u00eda para discernir las lecturas originales m\u00e1s veros\u00edmiles. Famosas ediciones cr\u00edticas del Nuevo Testamento griego son las Westcott y Hort (<em>1881<\/em>), la edici\u00f3n monumental de Von Soden en 1902-10.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"40585\" data-permalink=\"https:\/\/atravesdelasescrituras.com\/es_es\/nestlc3a9-aland\/\" data-orig-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/nestlc3a9-aland.jpg\" data-orig-size=\"332,446\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"nestlc3a9-aland\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/nestlc3a9-aland.jpg\" src=\"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/nestlc3a9-aland.jpg?resize=183%2C256&#038;ssl=1\" alt=\"\" class=\"wp-image-40585\" width=\"183\" height=\"256\" \/><figcaption>N.T Nestl\u00e9 Aland<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La edici\u00f3n de bolsillo m\u00e1s asequible y m\u00e1s veces reimpresa es la de Nestl\u00e9 Aland. En Espa\u00f1a tenemos una magn\u00edfica edici\u00f3n cr\u00edtica del Nuevo Testamento a cargo del P. J. M. Bover, SJ (<em>1943<\/em>).\u00a0<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>E) Las relaciones entre los c\u00f3dices:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los c\u00f3dices se agrupan en familias que suelen remontarse a\nuna recensi\u00f3n que luego es ampliamente copiada. La recensi\u00f3n es una edici\u00f3n\nmanuscrita cr\u00edtica que pretende atajar un estado lamentable del texto que se ha\nido corrompiendo por errores de los copistas. Dichas recensiones pueden\nlocalizarse en \u00e1reas geogr\u00e1ficas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Distinguen los especialistas cuatro tipos principales de\ntextos dentro de los cuales pueden catalogarse los manuscritos actualmente\nexistentes. Veamos un cuadro sin\u00f3ptico de dichos textos, seg\u00fan Streeter&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El texto alejandrino es el texto neutro y el de mejor calidad. Se fue formando en Egipto y est\u00e1 representado por los mejores c\u00f3dices unciales, el sina\u00edtico, Vaticano, el alejandrino (<em>menos los evangelios<\/em>), el palimpsesto C, el papiro 75. Evita armonizaciones y en general ofrece un texto breve sin ampliaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El texto occidental es un texto muy antiguo en el que\nabundan las interpolaciones. Est\u00e1 representado por el c\u00f3dice D, las antiguas\nversiones latina y sir\u00edaca, y los Padres de la Iglesia latina y otros como\nJustino y Taciano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El texto cesariense est\u00e1 relacionado con la obra de Or\u00edgenes\ny Eusebio. Se remonta al siglo III y est\u00e1 representado por los c\u00f3dices W y Q.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El texto bizantino proviene de alguna recensi\u00f3n realizada en\nel siglo V. Es m\u00e1s elegante y armonizante, y suele fusionar lecturas variantes.\nEs de hecho el que se ha venido usando en la Iglesia bizantina y el \u00fanico\nconocido durante la Edad Media. Se denomina tambi\u00e9n textus receptus.&nbsp;<\/p>\n\n\n\n<table class=\"wp-block-table aligncenter\"><tbody><tr><td>      <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" data-attachment-id=\"40582\" data-permalink=\"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/05\/23\/critica-textual-del-nuevo-testamento\/receptus\/\" data-orig-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/receptus.jpg\" data-orig-size=\"460,345\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"receptus\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/receptus.jpg\" class=\"wp-image-40582\" style=\"width:1000px;\" src=\"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/receptus.jpg?resize=1000%2C750&#038;ssl=1\" alt=\"undefined\"> <\/td><\/tr><\/tbody><\/table>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>F) Principios de cr\u00edtica textual:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Criterios de evidencia externa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que pesar las variantes seg\u00fan el valor de los c\u00f3dices\nque las sustentan. No siempre el criterio num\u00e9rico es el m\u00e1s importante. El\ncriterio num\u00e9rico sin m\u00e1s siempre dar\u00eda la raz\u00f3n al textus receptus. Hay que\ncomparar los manuscritos agrupados en familias seg\u00fan su relaci\u00f3n geneal\u00f3gica.\nTambi\u00e9n es interesante estudiar la distribuci\u00f3n geogr\u00e1fica de los textos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Criterios de evidencia interna:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se ha de estudiar qu\u00e9 variante concuerda mejor con el\nvocabulario, el estilo o la teolog\u00eda del autor. Se ha de ver qu\u00e9 variante\nencaja mejor en el contexto inmediato, y cu\u00e1l responde mejor al fondo arameo de\nlas palabras de Jes\u00fas, en el caso de los evangelios.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Reglas de cr\u00edtica textual:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dada la tendencia natural de los copistas a alargar m\u00e1s bien\nque acortar, a facilitar la lectura m\u00e1s bien que a dificultarla, y a concordar\ncon otros textos conocidos de memoria, podemos enunciar las siguientes reglas\ngenerales, que por supuesto nunca se pueden aplicar autom\u00e1ticamente.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Es preferible la lectura corta a la larga.<\/li><li>Es preferible la lectura dif\u00edcil a la f\u00e1cil.<\/li><li>Es preferible la lectura que no concuerda con los paralelos sin\u00f3pticos.<\/li><li>Es preferible aquella que puede explicar el origen de las dem\u00e1s.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>G) Algunos casos de cr\u00edtica textual dudosa\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los casos de variantes que afecten al sentido o a las ideas\nson m\u00ednimos. Detallaremos algunos de los principales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. El final largo de Marcos: Mc 16,9-20:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s el caso m\u00e1s significativo sea el del final can\u00f3nico de Marcos, o <em>\u201cfinal largo<\/em>\u201d de Marcos. En muchas traducciones modernas el evangelio de Marcos acaba en 16,8. El resto (<em>16,9-20<\/em>) se imprime en letra m\u00e1s peque\u00f1a o en una nota a pie de p\u00e1gina. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Falta en los c\u00f3dices Vaticano y Sina\u00edtico, pero est\u00e1 presente en el Alejandrino y en el c\u00f3dice de Beza. Falta en alguna versi\u00f3n sir\u00edaca, pero aparece en otras.. Est\u00e1 presente en el Diatessaron de Taciano, y al parecer Justino lo conoc\u00eda en el siglo II. Algunos Padres como Jer\u00f3nimo hicieron constar que faltaba en algunos de los manuscritos antiguos que consultaban. Para complicar m\u00e1s las cosas en algunos manuscritos aparecen otros finales alternativos, como el final corto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El an\u00e1lisis literario del final largo nos revela de que ni\nel vocabulario ni el estilo son propios de Marcos, y que se trata de un a\u00f1adido\nque no est\u00e1 hecho del mismo pa\u00f1o. Adem\u00e1s la transici\u00f3n entre el verso 8 y el 9\nes muy brusca con un cambio de sujeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte es raro que el evangelio de Marcos terminase en el vers\u00edculo 8 diciendo que las mujeres \u201c<em>ten\u00edan miedo\u201d. <\/em>No parece una manera normal de acabar un evangelio, aunque algunos te\u00f3logos den una gran importancia a este tema desde el punto de vista de la teolog\u00eda de Marcos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos m\u00e1s bien pensar que el final aut\u00e9ntico se ha perdido, y ha habido varios intentos m\u00e1s o menos logrados de subsanar la p\u00e9rdida, mediante la adici\u00f3n de otros finales m\u00e1s o menos logrados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. La ad\u00faltera: Jn 7,53-8,11:<\/p>\n\n\n\n<table class=\"wp-block-table aligncenter\"><tbody><tr><td>   &nbsp;   <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"650\" data-attachment-id=\"40583\" data-permalink=\"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/05\/23\/critica-textual-del-nuevo-testamento\/adultera2\/\" data-orig-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/adultera2.gif\" data-orig-size=\"346,225\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"adultera2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/adultera2.gif\" class=\"wp-image-40583\" style=\"width:1000px;\" src=\"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/adultera2.gif?resize=1000%2C650&#038;ssl=1\" alt=\"undefined\"> <\/td><td>\n  \n  <\/td><td>\n  &nbsp;\n  <\/td><\/tr><tr><td>V\u00e9ase la parte de abajo, que es el aparato cr\u00edtico correspondiente al pasaje de la ad\u00faltera, Jn 7,53-8,11.\u00a0 Primeramente bajo el rubro include aparecen los manuscritos que traen el texto: primero los unciales con may\u00fasculas y con n\u00fameros no comenzados en cero; luego los min\u00fasculos con n\u00fameros comenzados por cero;  luego la familia de c\u00f3dices Byzantina, luego las tradiciones al lat\u00edn it y vg,   al sirio syr, al copto cop, armenio y eti\u00f3pico; al final los Padres de la   Iglesia que citan o comentan este texto. <br><br>A continuaci\u00f3n vienen otras posibilidades, los c\u00f3dices que incluyen el texto entre asteriscos, luego la de los que lo incluyen al final de Jn 21: f13, o sea familia de manuscritos\u00a0 n\u00ba 13.  Al final, precedido por omit, vienen los c\u00f3dices que omiten este pasaje: son los mejores c\u00f3dices y los m\u00e1s antiguos: primero los papiros 66 y 75, luego los grandes unciales: sina\u00edtico, alejandrino, vaticano y otros muchos, luego los min\u00fasculos, luego los manuscritos de las traducciones, y finalmente los Padres que lo omiten.    <\/td><\/tr><\/tbody><\/table>\n\n\n\n<p class=\"wp-block-paragraph\">Es claramente una inserci\u00f3n posterior a la composici\u00f3n del\ncuarto evangelio. No aparece en los papiros Bodmer, ni en los grandes unciales\nVaticano y Sina\u00edtico, ni en la mayor parte de los unciales, ni en la Vetus\nLatina, ni en la traducci\u00f3n c\u00f3ptica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los autores griegos que comentan el evangelio de Juan se saltan este pasaje. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Omitiendo este pasaje se encadenan perfectamente Jn 7,52 con\n8,12. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estilo y vocabulario de este pasaje no son los propios de\nJuan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es s\u00f3lo la iglesia occidental donde fue admitido, en los\nc\u00f3dices occidentales, la edici\u00f3n Vulgata y los padres latinos como Jer\u00f3nimo y\nAgust\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos manuscritos griegos insertan este pasaje en el evangelio de Lucas entre 21,38 y 21,39. Curiosamente el estilo es mucho m\u00e1s propio de Lucas que de Juan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso los textos que lo incluyen en el evangelio de Juan\nno est\u00e1n de acuerdo en el lugar de su colocaci\u00f3n, y algunos lo sit\u00faan al final\ndel evangelio como un ap\u00e9ndice, y otros despu\u00e9s de 7,33.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La severidad con que la Iglesia primitiva penaba el\nadulterio pudo ser la causa de que durante alg\u00fan tiempo este pasaje fuese\ncensurado, y s\u00f3lo cuando se suaviz\u00f3 la disciplina penitencial tuvo cabida en el\ncanon. Y para este momento ya se habr\u00eda perdido la tradici\u00f3n sobre su verdadera\nubicaci\u00f3n, y se hicieron diversos intentos por situarlo en el evangelio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cualquier caso, aunque no se trate de un texto aut\u00e9ntico, (<em>original del evangelio<\/em>), sino de una interpolaci\u00f3n tard\u00eda, sin embargo s\u00ed se trata de un texto can\u00f3nico, por lo tanto inspirado, y la Iglesia en general lo propone como palabra de Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. El sudor de sangre: Lc 24,43-44<\/p>\n\n\n\n<table class=\"wp-block-table\"><tbody><tr><td>   &nbsp;   <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" data-attachment-id=\"40584\" data-permalink=\"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/05\/23\/critica-textual-del-nuevo-testamento\/getsemani\/\" data-orig-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/getsemani.jpg\" data-orig-size=\"460,345\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"getsemani\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/getsemani.jpg\" class=\"wp-image-40584\" style=\"width:1000px;\" src=\"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/getsemani.jpg?resize=1000%2C750&#038;ssl=1\" alt=\"undefined\"> <\/td><td>\n  \n  <\/td><td>\n  &nbsp;\n  <\/td><\/tr><tr><td>Vemos el aparato cr\u00edtico de los versos 43 y 44 de Lucas 22. Se trata del sudor de sangre, y del \u00e1ngel. Primeramente de enumeran los textos que los incluyen, luego los que los incluyen con asterisco, luego los que los trasponen despu\u00e9s de Mateo 26,39, y por \u00faltimo los que lo omiten, entre ellos un papiro, un corrector del   sina\u00edtico, el alejandrino, el vaticano, varias traducciones y varios Padres.   <\/td><\/tr><\/tbody><\/table>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSan Hilario, san Jer\u00f3nimo y san Cirilo\u00bb testimonian que en muchos c\u00f3dices de su \u00e9poca faltaba este texto, y efectivamente no est\u00e1 en muchos c\u00f3dices unciales m\u00e1s importantes. Tambi\u00e9n lo omite el papiro Bodmer p75 de hacia el a\u00f1o 200.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos piensan que este texto estaba en la versi\u00f3n original\ndel evangelio, pero que fue censurado durante una \u00e9poca, para que no fuese\nutilizado por los arrianos en su lucha contra la divinidad de Cristo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. El \u00e1ngel que mov\u00eda el agua de la piscina: Jn 5, 3b-5:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los principales c\u00f3dices griegos y originariamente la Vulgata\nlatina olvidan la referencia al descenso del \u00e1ngel. Tambi\u00e9n lo omite el papiro\nBodmer p66. Otros manuscritos proporcionan otras explicaciones de por qu\u00e9 el\n\u00e1ngel bajaba al agua. Muy probablemente se trata de una interpolaci\u00f3n tard\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. El trabajador en s\u00e1bado: Lc 6,4:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta vez se trata de un texto del manuscrito D, que no se\nrecoge en ning\u00fan otro manuscrito, y por tanto dif\u00edcilmente puede ser aut\u00e9ntico.\nSin embargo puede recoger un fragmento de tradici\u00f3n apost\u00f3lica sobre la vida de\nJes\u00fas. \u201cEncontr\u00e1ndose a uno que trabajaba en s\u00e1bado, le dijo: \u201cHombre, si sabes\nlo que est\u00e1s haciendo, bendito seas, pero si no lo sabes, caes bajo la\nmaldici\u00f3n de la ley\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. \u201cHa nacido\u201d vs. \u201chan nacido\u201d: Jn 1,13:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el pr\u00f3logo de san Juan unos pocos manuscritos leen \u201cha\nnacido de Dios\u201d, en singular, mientras que la inmensa mayor\u00eda lee \u201chan nacido\nde Dios\u201d, en plural. En este \u00faltimo caso se referir\u00eda al nacimiento de los\ncreyentes, pero si aceptamos el singular se estar\u00eda refiriendo al nacimiento\nvirginal de Jes\u00fas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7. \u00bfHombres de buena voluntad?: Lc 2, 14:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La traducci\u00f3n normal de este texto del Gloria, es \u201cen la\ntierra paz a los hombres de la buena voluntad (divina). La estructura es doble:\nGloria a Dios en el cielo, y paz en la tierra a los hombres. Esta traducci\u00f3n\nsupone un genitivo en la palabra eudok\u00eda (buena voluntad) que terminar\u00eda en\n\u201cs\u201d: eudok\u00edas. Sin embargo hay manuscritos en los que aparece en nominativo\n(sin la \u201cs\u201d), en cuyo caso la estructura del verbo ser\u00eda tripartita: Gloria a\nDios en el cielo, paz en la tierra, y eudok\u00eda a los hombres. El textus receptus\nlee eudok\u00eda en nominativo. En cambio los textos m\u00e1s antiguos traen eudok\u00edas en\ngenitivo, as\u00ed el Vaticano, Sina\u00edtico, Alejandrino, Beza, Vulgata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La evidencia externa favorece el genitivo, y tambi\u00e9n la interna, ya que el genitivo es la lectio m\u00e1s dif\u00edcil.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center;\"><a href=\"https:\/\/atravesdelasescrituras.com\/el-texto-biblico\/\">(Para ver las dem\u00e1s partes del estudio: El Texto B\u00edblico haz click aqu\u00ed)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A) Los Manuscritos del Nuevo Testamento 1. Papiros: Se nos conservan 118 papiros con textos o fragmentos del NT. Se citan con una p acompa\u00f1ada del n\u00famero del cat\u00e1logo. Son los manuscritos m\u00e1s antiguos. Los m\u00e1s importantes para el NT est\u00e1n en tres colecciones: Rylands (Manchester), por ejemplo p52 el fragmento m\u00e1s antiguo. Chester Beatty [&hellip;]<\/p>\n","protected":false},"author":80235555,"featured_media":40549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_gspb_post_css":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3908365],"tags":[3819944,543546,680251720,158926,680251713,5264106,680251719,680251768,10936780,10389688,680251697,615855,680251733,1214899,12952197,680251745,16990,291560497],"class_list":["post-40579","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-estudios-varios","tag-adultera","tag-bodmer","tag-cambios-intencionales","tag-chester-beatty","tag-citas-de-los-padres-de-la-iglesia","tag-critica-textual","tag-errores-de-copistas","tag-final-de-marcos","tag-minusculos","tag-nestle-aland","tag-nuevo-tsetamento","tag-objetivo","tag-p-j-m-bover","tag-rylands","tag-texto-alejandrino","tag-texto-occidental","tag-traducciones","tag-unciales","post_format-post-format-gallery"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5HWJ5-ayv","jetpack-related-posts":[{"id":49478,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2024\/05\/13\/transmision-del-texto-del-nuevo-testamento\/","url_meta":{"origin":40579,"position":0},"title":"Transmisi\u00f3n del texto del Nuevo Testamento","author":"Daniel L\u00f3pez","date":"13 May 2024","format":false,"excerpt":"El estudio del Nuevo Testamento es un desaf\u00edo complejo y fascinante que ha enfrentado desde sus or\u00edgenes numerosos obst\u00e1culos. A lo largo de los siglos, la distancia temporal, los cambios ling\u00fc\u00edsticos, culturales e hist\u00f3ricos, as\u00ed como la abundancia de comentarios y estudios, han hecho que esta tarea sea tanto m\u00e1s\u2026","rel":"","context":"En \u00abMis videos\u00bb","block_context":{"text":"Mis videos","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/videos\/mis-videos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40714,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/07\/05\/breve-introduccion-al-texto-griego-del-nuevo-testamento\/","url_meta":{"origin":40579,"position":1},"title":"Introducci\u00f3n al texto griego del Nuevo Testamento","author":"Daniel L\u00f3pez","date":"5 Jul 2019","format":"gallery","excerpt":"Cuando pensamos en el texto original del Nuevo Testamento, esto es, el texto griego escrito por inspirados hombres de Dios, lo primero que hacemos es preguntarnos cu\u00e1l es y d\u00f3nde est\u00e1, pues sabemos que nuestra versi\u00f3n mas com\u00fan Reina-Valera \u2015al igual que todas las versiones hechas en estos dos mil\u2026","rel":"","context":"En \u00abArt\u00edculos varios\u00bb","block_context":{"text":"Art\u00edculos varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/articulos-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/07\/introduccic3b3n-al-texto-griego-del-nuevo-testamento.jpg?fit=1200%2C514&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/07\/introduccic3b3n-al-texto-griego-del-nuevo-testamento.jpg?fit=1200%2C514&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/07\/introduccic3b3n-al-texto-griego-del-nuevo-testamento.jpg?fit=1200%2C514&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/07\/introduccic3b3n-al-texto-griego-del-nuevo-testamento.jpg?fit=1200%2C514&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/07\/introduccic3b3n-al-texto-griego-del-nuevo-testamento.jpg?fit=1200%2C514&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40682,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/06\/23\/padre-perdonalos-porque-no-saben-lo-que-hacen-dicho-de-jesus-critica-textual\/","url_meta":{"origin":40579,"position":2},"title":"\u00bfPadre perdonalos porque no saben lo que hacen? \u00bfDicho de Jes\u00fas? &#8211; Cr\u00edtica textual","author":"Daniel L\u00f3pez","date":"23 Jun 2019","format":"gallery","excerpt":"Los cristianos contemplan las palabras pronunciadas por Jesus durante su crucifixi\u00f3n, se puede observar detenidamente la variante textual en Lucas 23: 34a, donde, en casi todos los manuscritos griegos tard\u00edos, en la Vulgata latina y la Peshitta, estas palabras de Jes\u00fas est\u00e1n registradas: \u201cPadre, perd\u00f3nalos, porque no saben lo que\u2026","rel":"","context":"En \u00abArt\u00edculos varios\u00bb","block_context":{"text":"Art\u00edculos varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/articulos-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/06\/img_0988.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/06\/img_0988.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/06\/img_0988.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/06\/img_0988.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":57863,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2026\/08\/26\/preguntas-y-respuestas-6\/","url_meta":{"origin":40579,"position":3},"title":"Preguntas y respuestas #6 \u00bfPor qu\u00e9 el Nuevo Testamento cita algunas veces el Tanaj de manera diferente?","author":"Daniel L\u00f3pez","date":"26 Ago 2026","format":false,"excerpt":"Bienvenido a esta secci\u00f3n de preguntas y respuestas de A trav\u00e9s de las Escrituras. Aqu\u00ed examinamos cuestiones b\u00edblicas desde una perspectiva mesi\u00e1nica, reconociendo a Yesh\u00faa de Nazaret como el Mes\u00edas de Israel y leyendo el Nuevo Testamento dentro de su contexto cultural jud\u00edo, hist\u00f3rico y literario. Nuestro prop\u00f3sito no es\u2026","rel":"","context":"En \u00abPreguntas y Respuestas\u00bb","block_context":{"text":"Preguntas y Respuestas","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/preguntas-y-respuestas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2026\/08\/Por-que-el-Nuevo-Testamento-cita-algunas-veces-el-Tanaj-de-manera-diferente.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2026\/08\/Por-que-el-Nuevo-Testamento-cita-algunas-veces-el-Tanaj-de-manera-diferente.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2026\/08\/Por-que-el-Nuevo-Testamento-cita-algunas-veces-el-Tanaj-de-manera-diferente.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2026\/08\/Por-que-el-Nuevo-Testamento-cita-algunas-veces-el-Tanaj-de-manera-diferente.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2026\/08\/Por-que-el-Nuevo-Testamento-cita-algunas-veces-el-Tanaj-de-manera-diferente.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":23185,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2016\/10\/02\/evidencias-arqueologicas\/","url_meta":{"origin":40579,"position":4},"title":"5. Evidencias arqueologicas","author":"Daniel L\u00f3pez","date":"2 Oct 2016","format":"gallery","excerpt":"No cabe duda que ningu\u0301n otro libro de los que se consideran como sagrados ha sido ma\u0301s atacado y controvertido que la Biblia. Muchos de sus cri\u0301ticos argumentan que hubo un gran intervalo de tiempo entre los eventos ocurridos en el Nuevo Testamento y cuando fueron escritos sus originales. Tambie\u0301n\u2026","rel":"","context":"En \u00abEstudios Varios\u00bb","block_context":{"text":"Estudios Varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/estudios-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/10\/pilato-inscripcion.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":40560,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2019\/05\/22\/palabra-escrita\/","url_meta":{"origin":40579,"position":5},"title":"Palabra escrita","author":"Daniel L\u00f3pez","date":"22 May 2019","format":"gallery","excerpt":"Formas de escritura: 1. Evoluci\u00f3n de la escritura: Los investigadores de la escritura describen una evoluci\u00f3n desde el pictograma m\u00e1s o menos realista y\/o art\u00edstico hasta el logotipo, que es una simplificaci\u00f3n del realismo pictogr\u00e1fico, sujeto a m\u00faltiples convencionalismos: por ejemplo, un tipo de sol puede designar el d\u00eda o\u2026","rel":"","context":"En \u00abEstudios Varios\u00bb","block_context":{"text":"Estudios Varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/estudios-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/texto-bicc81blico.jpg?fit=1200%2C471&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/texto-bicc81blico.jpg?fit=1200%2C471&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/texto-bicc81blico.jpg?fit=1200%2C471&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/texto-bicc81blico.jpg?fit=1200%2C471&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/texto-bicc81blico.jpg?fit=1200%2C471&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"brizy_media":[],"jetpack_featured_media_url":"https:\/\/atravesdelasescrituras.com\/wp-content\/uploads\/2019\/05\/texto-bicc81blico.jpg","_links":{"self":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/40579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/users\/80235555"}],"replies":[{"embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/comments?post=40579"}],"version-history":[{"count":1,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/40579\/revisions"}],"predecessor-version":[{"id":40586,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/40579\/revisions\/40586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/media\/40549"}],"wp:attachment":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/media?parent=40579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/categories?post=40579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/tags?post=40579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}