{"id":42295,"date":"2020-07-17T13:39:08","date_gmt":"2020-07-17T13:39:08","guid":{"rendered":"http:\/\/atravesdelasescrituras.com\/?p=42295"},"modified":"2020-07-17T13:39:08","modified_gmt":"2020-07-17T13:39:08","slug":"introduccion-a-el-libro-de-los-hechos-1a-parte","status":"publish","type":"post","link":"https:\/\/atravesdelasescrituras.com\/es_es\/2020\/07\/17\/introduccion-a-el-libro-de-los-hechos-1a-parte\/","title":{"rendered":"Introducci\u00f3n a el libro de los Hechos 1\u00aa Parte"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-0 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Introducci\u00f3n al libro de los Hechos, Autor, Fecha, Cronolog\u00eda en tiempos del Nuevo Testamento, Bosquejo, Critica textual y algunos detalles mas antes de comenzar a este estupendo libro \u00ab\u00fanico\u00bb que relata la historia de los Hechos despu\u00e9s del derramamiento de la promesa \u00abRuaj Haqodesh\u00bb y como El Eterno uso a los ap\u00f3stoles para extender el reino y las buenas nuevas de salvaci\u00f3n para TODOS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas info en: <a href=\"http:\/\/www.Beneytzion.com\" rel=\"nofollow\">http:\/\/www.Beneytzion.com<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" width=\"1870\" height=\"1052\" src=\"https:\/\/www.youtube.com\/embed\/SJD-h_jiwgM?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;start=4848&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Introducci\u00f3n al libro de los Hechos, Autor, Fecha, Cronolog\u00eda en tiempos del Nuevo Testamento, Bosquejo, Critica textual y algunos detalles mas antes de comenzar a este estupendo libro \u00ab\u00fanico\u00bb que relata la historia de los Hechos despu\u00e9s del derramamiento de la promesa \u00abRuaj Haqodesh\u00bb y como El Eterno uso a los ap\u00f3stoles para extender el [&hellip;]<\/p>\n","protected":false},"author":80235555,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_gspb_post_css":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[154090,1149],"tags":[14316,676219131,21619934,5264106,5293269,825028,9197,3503,680465496,862164,634736149,702624112],"class_list":["post-42295","post","type-post","status-publish","format-standard","hentry","category-mis-videos","category-videos","tag-autor","tag-beney-tzion","tag-cesares","tag-critica-textual","tag-cronologia-biblica","tag-fecha","tag-fuentes","tag-historia","tag-historia-del-primer-siglo","tag-procuradores","tag-ruaj-haqodesh","tag-tiempos-de-hechos"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5HWJ5-b0b","jetpack-related-posts":[{"id":42407,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2020\/08\/06\/introduccion-a-el-libro-de-los-hechos-2a-parte\/","url_meta":{"origin":42295,"position":0},"title":"Introducci\u00f3n a el libro de los Hechos 2\u00aa Parte","author":"Daniel L\u00f3pez","date":"6 Ago 2020","format":false,"excerpt":"Introducci\u00f3n al libro de los Hechos, Autor, Fecha, Cronolog\u00eda en tiempos del Nuevo Testamento, Bosquejo, Critica textual y algunos detalles mas antes de comenzar a este estupendo libro \"\u00fanico\" que relata la historia de los Hechos despu\u00e9s del derramamiento de la promesa \"Ruaj Haqodesh\" y como El Eterno uso a\u2026","rel":"","context":"En \u00abMis videos\u00bb","block_context":{"text":"Mis videos","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/videos\/mis-videos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/qpvPvwbNng4\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":39795,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2018\/05\/20\/que-se-celebra-en-shavout\/","url_meta":{"origin":42295,"position":1},"title":"\u00bfQue se celebra en Shavout?","author":"Daniel L\u00f3pez","date":"20 May 2018","format":false,"excerpt":"La festividad acaece el 6 de Siv\u00e1n del calendario hebreo, exactamente 7 semanas despu\u00e9s del segundo d\u00eda de P\u00e9saj (16 de Abib o Nis\u00e1n). El nombre de la festividad tiene su origen en este hecho (Shavuot - \u05e9\u05d1\u05d5\u05e2\u05d5\u05ea - plural de Shav\u00faa - \u05e9\u05d1\u05d5\u05e2, semana.) La festividad conmemora la entrega\u2026","rel":"","context":"En \u00abMis videos\u00bb","block_context":{"text":"Mis videos","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/videos\/mis-videos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/PW8dXUXNMdg\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":49478,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2024\/05\/13\/transmision-del-texto-del-nuevo-testamento\/","url_meta":{"origin":42295,"position":2},"title":"Transmisi\u00f3n del texto del Nuevo Testamento","author":"Daniel L\u00f3pez","date":"13 May 2024","format":false,"excerpt":"El estudio del Nuevo Testamento es un desaf\u00edo complejo y fascinante que ha enfrentado desde sus or\u00edgenes numerosos obst\u00e1culos. A lo largo de los siglos, la distancia temporal, los cambios ling\u00fc\u00edsticos, culturales e hist\u00f3ricos, as\u00ed como la abundancia de comentarios y estudios, han hecho que esta tarea sea tanto m\u00e1s\u2026","rel":"","context":"En \u00abMis videos\u00bb","block_context":{"text":"Mis videos","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/videos\/mis-videos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2024\/05\/trasmision-del-nuevo-testamneto.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55714,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2025\/10\/27\/el-dia-de-la-ultima-cena-analisis-historico-exegetico-y-teologico-de-la-cronologia-pascual-en-los-evangelios\/","url_meta":{"origin":42295,"position":3},"title":"\u201cEl D\u00eda de la \u00daltima Cena: An\u00e1lisis hist\u00f3rico, exeg\u00e9tico y teol\u00f3gico de la cronolog\u00eda pascual en los Evangelios\u201d","author":"Daniel L\u00f3pez","date":"27 Oct 2025","format":false,"excerpt":"Entre los episodios m\u00e1s enigm\u00e1ticos de la Pasi\u00f3n de Cristo, ninguno ha suscitado tantas discusiones acad\u00e9micas como la fecha exacta en que Jes\u00fas celebr\u00f3 su \u00daltima Cena. A primera vista, la divergencia entre los Evangelios parece insalvable: mientras los Evangelios sin\u00f3pticos (Mateo, Marcos y Lucas) presentan la cena como una\u2026","rel":"","context":"En \u00abArt\u00edculos varios\u00bb","block_context":{"text":"Art\u00edculos varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/articulos-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2025\/10\/la-ultima-cena-de-jesus.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2025\/10\/la-ultima-cena-de-jesus.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2025\/10\/la-ultima-cena-de-jesus.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2025\/10\/la-ultima-cena-de-jesus.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2025\/10\/la-ultima-cena-de-jesus.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8143,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2016\/06\/20\/testimonios-no-cristianos-de-la-existencia-de-jesus-de-nazaret\/","url_meta":{"origin":42295,"position":4},"title":"Testimonios no cristianos de la existencia de Jes\u00fas de Nazaret","author":"Daniel L\u00f3pez","date":"20 Jun 2016","format":"gallery","excerpt":"No fue considerado significativo para los historiadores de su tiempo aunque Flavio Josefo y T\u00e1cito se refieren a Cristo en sus escritos \u00bfPadeci\u00f3 bajo el poder de Poncio Pilato? De la existencia de Jes\u00fas de Nazareth no duda ning\u00fan historiador serio. Para el historiador especializado en culturas antiguas\u00a0Michael Grant, ya\u2026","rel":"","context":"En \u00abArt\u00edculos varios\u00bb","block_context":{"text":"Art\u00edculos varios","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/articulos-varios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/06\/evidencias-de-la-existencia-de-jesus-6_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/06\/evidencias-de-la-existencia-de-jesus-6_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2016\/06\/evidencias-de-la-existencia-de-jesus-6_0.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":44264,"url":"https:\/\/atravesdelasescrituras.com\/es_es\/2023\/09\/03\/introduccion-a-la-serie-uso-del-antiguo-testamento-en-el-nuevo-testamento\/","url_meta":{"origin":42295,"position":5},"title":"Introducci\u00f3n a la Serie &#8211; Uso del Antiguo Testamento en el Nuevo Testamento","author":"Daniel L\u00f3pez","date":"3 Sep 2023","format":false,"excerpt":"En este primer video de la Serie: (Uso del A.T en el N.T) haremos una introducci\u00f3n al material que estaremos utilizando para esta serie titulado: Commentary on the New Testament use of the Old Testament (Grand Rapids, MI; Nottingham, UK: Baker Academic; Apollos, 2007), 35.","rel":"","context":"En \u00abMis videos\u00bb","block_context":{"text":"Mis videos","link":"https:\/\/atravesdelasescrituras.com\/es_es\/category\/videos\/mis-videos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2023\/09\/portada-uso-del-antiguo-testamento-6.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2023\/09\/portada-uso-del-antiguo-testamento-6.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2023\/09\/portada-uso-del-antiguo-testamento-6.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2023\/09\/portada-uso-del-antiguo-testamento-6.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/atravesdelasescrituras.com\/wp-content\/uploads\/2023\/09\/portada-uso-del-antiguo-testamento-6.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"brizy_media":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/42295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/users\/80235555"}],"replies":[{"embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/comments?post=42295"}],"version-history":[{"count":2,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/42295\/revisions"}],"predecessor-version":[{"id":42416,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/posts\/42295\/revisions\/42416"}],"wp:attachment":[{"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/media?parent=42295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/categories?post=42295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atravesdelasescrituras.com\/es_es\/wp-json\/wp\/v2\/tags?post=42295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}